{"id":2511,"date":"2024-02-01T12:10:08","date_gmt":"2024-02-01T11:10:08","guid":{"rendered":"https:\/\/gorgesdelareuse.ch\/?page_id=2511"},"modified":"2026-07-25T10:26:51","modified_gmt":"2026-07-25T08:26:51","slug":"contact","status":"publish","type":"page","link":"https:\/\/gorgesdelareuse.ch\/de\/contact\/","title":{"rendered":"Contact"},"content":{"rendered":"<p><strong>Adresse du secr\u00e9tariat<\/strong><br \/>\nSoci\u00e9t\u00e9 des Sentiers des Gorges de l\u2019Areuse<br \/>\nCase postale<br \/>\nCH &#8211; 2024 Saint-Aubin-Sauges<br \/>\nE-mail : info (at) gorgesdelareuse.ch<\/p>\n<p><strong>Vos dons<\/strong><br \/>\nIBAN: CH74 0900 0000 2000 3454 2<br \/>\nBIC POFICHBEXXX<\/p>\n<p><strong>Dons par TWINT<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2759\" src=\"http:\/\/gorgesdelareuse.ch\/wp-content\/uploads\/2026\/06\/TWINT-SSGA-182x300.jpg\" alt=\"\" width=\"119\" height=\"196\" srcset=\"https:\/\/gorgesdelareuse.ch\/wp-content\/uploads\/2026\/06\/TWINT-SSGA-182x300.jpg 182w, https:\/\/gorgesdelareuse.ch\/wp-content\/uploads\/2026\/06\/TWINT-SSGA.jpg 246w\" sizes=\"(max-width: 119px) 100vw, 119px\" \/><\/p>\n<p><strong>Adh\u00e9sion<br \/>\n<\/strong>En devenant membre de notre soci\u00e9t\u00e9, vous manifestez votre int\u00e9r\u00eat pour cette magnifique contr\u00e9e et vous recevrez chaque ann\u00e9e, notre d\u00e9pliant comprenant de nouvelles informations.<\/p>\n<p>Cotisation annuelle pour membre individuel : CHF 25.-<br \/>\nCotisation annuelle pour famille : CHF 30.-<\/p>\n<p>D\u00e8s r\u00e9ception de votre demande d\u2019adh\u00e9sion, vous recevrez les informations annuelles ainsi qu\u2019un bulletin de versement pour vous acquitter du montant de la cotisation.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Adresse du secr\u00e9tariat Soci\u00e9t\u00e9 des Sentiers des Gorges de l\u2019Areuse Case postale CH &#8211; 2024 Saint-Aubin-Sauges E-mail : info (at) gorgesdelareuse.ch Vos dons IBAN: CH74 0900 0000 2000 3454 2 BIC POFICHBEXXX Dons par TWINT Adh\u00e9sion En devenant membre de notre soci\u00e9t\u00e9, vous manifestez votre int\u00e9r\u00eat pour cette magnifique contr\u00e9e et vous recevrez chaque ann\u00e9e, &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/gorgesdelareuse.ch\/de\/contact\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eContact\u201c <\/span>weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-2511","page","type-page","status-publish","hentry"],"translation":{"provider":"WPGlobus","version":"3.0.5","language":"de","enabled_languages":["fr","de"],"languages":{"fr":{"title":true,"content":true,"excerpt":false},"de":{"title":false,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/gorgesdelareuse.ch\/de\/wp-json\/wp\/v2\/pages\/2511","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gorgesdelareuse.ch\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/gorgesdelareuse.ch\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/gorgesdelareuse.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gorgesdelareuse.ch\/de\/wp-json\/wp\/v2\/comments?post=2511"}],"version-history":[{"count":9,"href":"https:\/\/gorgesdelareuse.ch\/de\/wp-json\/wp\/v2\/pages\/2511\/revisions"}],"predecessor-version":[{"id":2812,"href":"https:\/\/gorgesdelareuse.ch\/de\/wp-json\/wp\/v2\/pages\/2511\/revisions\/2812"}],"wp:attachment":[{"href":"https:\/\/gorgesdelareuse.ch\/de\/wp-json\/wp\/v2\/media?parent=2511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}